{"id":5828,"date":"2026-04-10T15:39:32","date_gmt":"2026-04-10T07:39:32","guid":{"rendered":"https:\/\/recyclingmachinery.org\/?p=5828"},"modified":"2026-04-10T15:40:18","modified_gmt":"2026-04-10T07:40:18","slug":"specific-gravity-separator","status":"publish","type":"post","link":"https:\/\/recyclingmachinery.org\/de\/specific-gravity-separator\/","title":{"rendered":"Schweregradseparator f\u00fcr Kupfer- &amp; Kunststoffrecycling"},"content":{"rendered":"<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-top\"     data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;5828&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;29&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;4.6&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;4.6\\\/5 - (29 votes)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;Specific Gravity Separator for Copper \\u0026amp; Plastic Recycling&quot;,&quot;width&quot;:&quot;130.9&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>              <div class=\"kksr-stars\">      <div class=\"kksr-stars-inactive\">             <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>     <\/div>      <div class=\"kksr-stars-active\" style=\"width: 130.9px;\">             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>     <\/div> <\/div>                   <div class=\"kksr-legend\" style=\"font-size: 19.2px;\">             4.6\/5 - (29 Stimmen)    <\/div>     <\/div>  <p class=\"wp-block-paragraph\">Der Schweregradseparator wird verwendet, um Nichteisenmetalle von Nichtmetallen zu trennen, und ist in der Schrott-Recyclingbranche weit verbreitet. Er eignet sich besonders zum Trennen von Kupfer von Kunststoff nach dem Zerkleinern von Schrottdr\u00e4hten und -kabeln sowie zum Trennen von Kupfer, Aluminium und Eisen nach dem Zerkleinern von Kupfer-Aluminium-K\u00fchlern.<\/p>    <p class=\"wp-block-paragraph\">Das Ger\u00e4t verf\u00fcgt \u00fcber ein integriertes, kompaktes Design mit kleiner Grundfl\u00e4che. Es kann direkt auf einer ebenen Fl\u00e4che platziert, eingesteckt und sofort betrieben werden, was es f\u00fcr den Einsatz in kleinen bis mittelgro\u00dfen und gro\u00dfen Recyclingproduktionslinien geeignet macht.<\/p>    <p class=\"wp-block-paragraph\">Als Kernkomponente des Feintrennprozesses in Kupfergranulat-Produktionssystemen kombiniert die Ausr\u00fcstung Luftstromsuspension mit dem Prinzip der Dichteunterschiede. In Kombination mit einem elektrostatischen Trennsystem kann die Kupfer-R\u00fcckgewinnungsreinheit konstant 99,5 % oder h\u00f6her erreichen. Dies reduziert den verbleibenden Kupferanteil im Kunststoff weiter und stellt sicher, dass die Endsortierung den hohen Standard \u201eKein Kunststoff im Kupfer, kein Kupfer im Kunststoff\u201c erf\u00fcllt.<\/p>    <h2 class=\"wp-block-heading\">Anwendungen des Schweregradseparators<\/h2>    <ul class=\"wp-block-list\"> <li>Sortierung von Kupfer und Kunststoff aus zerkleinertem Schrottkabeln und -dr\u00e4hten.<\/li>    <li>Sortierung von Kupfer, Aluminium und Eisen aus zerkleinerten Kupfer-Aluminium-K\u00fchlern.<\/li>    <li>Feine Metallreinigungsprozesse in Kupfergranulat-Produktionslinien.<\/li>    <li>Die Recycling- und Umweltbehandlungsbranche.<\/li> <\/ul>    <figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"> <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" data-id=\"5833\" src=\"https:\/\/recyclingmachinery.org\/wp-content\/uploads\/2026\/04\/air-gravity-separator-for-copper-recycling.webp\" alt=\"Luft-Schwerkraftseparator f\u00fcr Kupferrecycling\" class=\"wp-image-5833\" srcset=\"https:\/\/recyclingmachinery.org\/wp-content\/uploads\/2026\/04\/air-gravity-separator-for-copper-recycling.webp 720w, https:\/\/recyclingmachinery.org\/wp-content\/uploads\/2026\/04\/air-gravity-separator-for-copper-recycling-480x360.webp 480w, https:\/\/recyclingmachinery.org\/wp-content\/uploads\/2026\/04\/air-gravity-separator-for-copper-recycling-360x270.webp 360w, https:\/\/recyclingmachinery.org\/wp-content\/uploads\/2026\/04\/air-gravity-separator-for-copper-recycling-16x12.webp 16w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">Luft-Schwerkraftseparator f\u00fcr Kupferrecycling<\/figcaption><\/figure>    <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" data-id=\"5834\" src=\"https:\/\/recyclingmachinery.org\/wp-content\/uploads\/2026\/04\/copper-plastic-separator-machine.webp\" alt=\"Kupfer-Kunststoff-Separator Maschine\" class=\"wp-image-5834\" srcset=\"https:\/\/recyclingmachinery.org\/wp-content\/uploads\/2026\/04\/copper-plastic-separator-machine.webp 720w, https:\/\/recyclingmachinery.org\/wp-content\/uploads\/2026\/04\/copper-plastic-separator-machine-480x360.webp 480w, https:\/\/recyclingmachinery.org\/wp-content\/uploads\/2026\/04\/copper-plastic-separator-machine-360x270.webp 360w, https:\/\/recyclingmachinery.org\/wp-content\/uploads\/2026\/04\/copper-plastic-separator-machine-16x12.webp 16w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">Kupfer-Kunststoff-Separator Maschine<\/figcaption><\/figure> <\/figure>    <h2 class=\"wp-block-heading\">Strukturelle Merkmale der Schwerkraftseparator-Maschine<\/h2>    <ul class=\"wp-block-list\"> <li>Das integrierte Strukturdesign ist kompakt und gut organisiert, was den Transport und die Installation erleichtert.<\/li>    <li>Das PLC-Automatiksteuerungssystem sorgt f\u00fcr einen stabilen Betrieb und einfache Handhabung.<\/li>    <li>Erreicht hohe Trennungseffizienz durch ein Luftsuspensions-Dichte-Trennverfahren.<\/li>    <li>SKD-11 Legierungsschneidwerkzeug-Zerkleinerungssystem mit einer H\u00e4rte von bis zu HRC 58.<\/li>    <li>Die wechselnde \u201eFigure-eight\u201c-Schneidstruktur erh\u00f6ht die Zerkleinerungseffizienz und Stabilit\u00e4t.<\/li>    <li>Das wassergek\u00fchlte Systemdesign verhindert effektiv das Schmelzen des Materials bei hohen Temperaturen.<\/li>    <li>Vollst\u00e4ndig geschlossene Maschinenstruktur reduziert das Risiko der Verbreitung von Kontaminationen.<\/li>    <li>Ausgestattet mit einem Pulsstaubsammelsystem f\u00fcr die zentrale Staubbehandlung.<\/li> <\/ul>    <h2 class=\"wp-block-heading\">Vorteile der Dichte-Trennmaschine<\/h2>    <ul class=\"wp-block-list\"> <li>Hohe Sortiergenauigkeit: Verbessert effektiv die Trennung von Kupfer, Kunststoff und Metallmischungen.<\/li>    <li>Energieeffizient und umweltfreundlich: Geschlossener Betrieb in Kombination mit einem Staubsammelsystem reduziert Staubverschmutzung.<\/li>    <li>Hohe Automatisierungsgrad: PLC-Steuerung reduziert die Abh\u00e4ngigkeit von manueller Arbeit.<\/li>    <li>Hohe Stabilit\u00e4t: Geeignet f\u00fcr langfristige kontinuierliche Produktion.<\/li>    <li>Breite Anpassungsf\u00e4higkeit: Luftstrom und Vibrationsfrequenz k\u00f6nnen an unterschiedliche Materialien angepasst werden.<\/li>    <li>Hoher R\u00fcckgewinnungsgrad: In Verbindung mit elektrostatischer Trenntechnik reduziert es den Kupferpulververlust um 3\u20135 %.<\/li> <\/ul>    <h2 class=\"wp-block-heading\">Funktionsprinzip des Schweregradseparators<\/h2>    <p class=\"wp-block-paragraph\">Das Ger\u00e4t nutzt Unterschiede in der Materialdichte als Kernprinzip der Sortierung. Ein vibrierendes F\u00f6rdersystem verteilt die zerkleinerte Mischung gleichm\u00e4\u00dfig, w\u00e4hrend eine Luftfederungseinrichtung Materialien unterschiedlicher Dichte durch den Luftstrom in unterschiedliche Schichten formt.<\/p>    <p class=\"wp-block-paragraph\">Schwerere Metallpartikel (wie Kupfer und Aluminium) setzen sich unter dem Einfluss der Schwerkraft ab und werden gesammelt, w\u00e4hrend leichtere Kunststoffe durch den Luftstrom zu verschiedenen Ausg\u00e4ngen transportiert werden, was eine effiziente Trennung erm\u00f6glicht. Durch Anpassung der Vibrationsfrequenz und Luftstromintensit\u00e4t kann das System sich an unterschiedliche Materialzusammensetzungen anpassen und pr\u00e4zise sortieren.<\/p>    <figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"> <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"405\" height=\"540\" data-id=\"5835\" src=\"https:\/\/recyclingmachinery.org\/wp-content\/uploads\/2026\/04\/specific-gravity-separator-machine-405x540.webp\" alt=\"Schweregradseparator-Maschine\" class=\"wp-image-5835\" srcset=\"https:\/\/recyclingmachinery.org\/wp-content\/uploads\/2026\/04\/specific-gravity-separator-machine-405x540.webp 405w, https:\/\/recyclingmachinery.org\/wp-content\/uploads\/2026\/04\/specific-gravity-separator-machine-270x360.webp 270w, https:\/\/recyclingmachinery.org\/wp-content\/uploads\/2026\/04\/specific-gravity-separator-machine-9x12.webp 9w, https:\/\/recyclingmachinery.org\/wp-content\/uploads\/2026\/04\/specific-gravity-separator-machine.webp 540w\" sizes=\"auto, (max-width: 405px) 100vw, 405px\" \/><figcaption class=\"wp-element-caption\">Schweregradseparator-Maschine<\/figcaption><\/figure>    <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"405\" height=\"540\" data-id=\"5836\" src=\"https:\/\/recyclingmachinery.org\/wp-content\/uploads\/2026\/04\/waste-wire-recycling-machine-separator-405x540.webp\" alt=\"Abfallkabel-Recyclingmaschine Separator\" class=\"wp-image-5836\" srcset=\"https:\/\/recyclingmachinery.org\/wp-content\/uploads\/2026\/04\/waste-wire-recycling-machine-separator-405x540.webp 405w, https:\/\/recyclingmachinery.org\/wp-content\/uploads\/2026\/04\/waste-wire-recycling-machine-separator-270x360.webp 270w, https:\/\/recyclingmachinery.org\/wp-content\/uploads\/2026\/04\/waste-wire-recycling-machine-separator-9x12.webp 9w, https:\/\/recyclingmachinery.org\/wp-content\/uploads\/2026\/04\/waste-wire-recycling-machine-separator.webp 540w\" sizes=\"auto, (max-width: 405px) 100vw, 405px\" \/><figcaption class=\"wp-element-caption\">Abfallkabel-Recyclingmaschine Separator<\/figcaption><\/figure> <\/figure>    <h2 class=\"wp-block-heading\">Technische Details<\/h2>    <figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><tbody><tr><td>Artikel<\/td><td>Spezifikation<\/td><\/tr><tr><td>Modell<\/td><td>Schweregradseparator<\/td><\/tr><tr><td>Anwendung<\/td><td>Kupfer-Kunststoff \/ Metallsortierung<\/td><\/tr><tr><td>Steuerungssystem<\/td><td>PLC-Automatiksteuerung<\/td><\/tr><tr><td>Trennmethode<\/td><td>Luftfederung   Schwerkrafttrennung<\/td><\/tr><tr><td>Klingenmaterial<\/td><td>SKD-11 Legierungsstahl<\/td><\/tr><tr><td>Klingenh\u00e4rte<\/td><td>HR58<\/td><\/tr><tr><td>K\u00fchlsystem<\/td><td>Wasserk\u00fchlsystem<\/td><\/tr><tr><td>Staubabsaugung<\/td><td>Pulsstaubsammelsystem<\/td><\/tr><tr><td>Strukturtyp<\/td><td>Integrierte kompakte Struktur<\/td><\/tr><tr><td>Betriebsmodus<\/td><td>Vollst\u00e4ndig geschlossenes Dauerbetriebssystem<\/td><\/tr><tr><td>Bedieneranforderung<\/td><td>1 Bediener<\/td><\/tr><\/tbody><\/table><figcaption class=\"wp-element-caption\">Detaillierte technische Informationen des Schweregradseparators<\/figcaption><\/figure>    <h2 class=\"wp-block-heading\">Anwendungen in Produktionslinien<\/h2>    <p class=\"wp-block-paragraph translation-block\">In praktischen Anwendungen dienen Schweregradseparatoren typischerweise als Schl\u00fcssel-Sortierger\u00e4te und sind weit in <a href=\"https:\/\/recyclingmachinery.org\/de\/copper-aluminum-radiator-recycling-line\/\">Kupfer-Aluminium-K\u00fchler-Recyclinglinien<\/a> und <a href=\"https:\/\/recyclingmachinery.org\/de\/circuit-boards-crusher-and-separator\/\">Leiterplatten-Recyclingproduktionslinien<\/a> integriert. Sie arbeiten effizient in Synergie mit Zerkleinerungs-, Luftklassifizierungs- und elektrostatischen Trennsystemen.<\/p>    <p class=\"wp-block-paragraph\">Durch die nahtlose Integration mehrerer Sortierprozesse verbessert dieser Ansatz nicht nur die Reinheit der Metallr\u00fcckgewinnung und die Ressourcennutzung erheblich, sondern reduziert auch effektiv die Arbeitskosten und Umweltverschmutzungsrisiken. Bitte kontaktieren Sie uns f\u00fcr Ihre Produktionslinienkonfiguration.<\/p>","protected":false},"excerpt":{"rendered":"<p>Der Schweregradseparator ist eine effiziente L\u00f6sung f\u00fcr Recyclinglinien, die eine hochreine Trennung von Kupfer, Kunststoff und gemischten Metallen erm\u00f6glicht. Mit PLC-Steuerung, Luftfederungstechnologie und integriertem Design sorgt er f\u00fcr einen stabilen Betrieb, reduzierte Arbeitskosten und verbesserte R\u00fcckgewinnungsraten bei der Recycling von Dr\u00e4hten und Leiterplatten.<\/p>","protected":false},"author":1,"featured_media":5837,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1,36],"tags":[80,63,62],"class_list":["post-5828","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recycling-equipment","category-metal-recycling-machines","tag-aluminum","tag-copper","tag-metal"],"taxonomy_info":{"category":[{"value":1,"label":"Recycling Equipment"},{"value":36,"label":"Metal Recycling Machines"}],"post_tag":[{"value":80,"label":"aluminum"},{"value":63,"label":"copper"},{"value":62,"label":"metal"}]},"featured_image_src_large":["https:\/\/recyclingmachinery.org\/wp-content\/uploads\/2026\/04\/recycling-gravity-separation-equipment.webp",720,540,false],"author_info":{"display_name":"Lolita","author_link":"https:\/\/recyclingmachinery.org\/de\/author\/rmachinery_o\/"},"comment_info":0,"category_info":[{"term_id":1,"name":"Recycling Equipment","slug":"recycling-equipment","term_group":0,"term_taxonomy_id":1,"taxonomy":"category","description":"","parent":0,"count":67,"filter":"raw","cat_ID":1,"category_count":67,"category_description":"","cat_name":"Recycling Equipment","category_nicename":"recycling-equipment","category_parent":0},{"term_id":36,"name":"Metal Recycling Machines","slug":"metal-recycling-machines","term_group":0,"term_taxonomy_id":36,"taxonomy":"category","description":"","parent":1,"count":13,"filter":"raw","cat_ID":36,"category_count":13,"category_description":"","cat_name":"Metal Recycling Machines","category_nicename":"metal-recycling-machines","category_parent":1}],"tag_info":[{"term_id":80,"name":"aluminum","slug":"aluminum","term_group":0,"term_taxonomy_id":80,"taxonomy":"post_tag","description":"","parent":0,"count":10,"filter":"raw"},{"term_id":63,"name":"copper","slug":"copper","term_group":0,"term_taxonomy_id":63,"taxonomy":"post_tag","description":"","parent":0,"count":8,"filter":"raw"},{"term_id":62,"name":"metal","slug":"metal","term_group":0,"term_taxonomy_id":62,"taxonomy":"post_tag","description":"","parent":0,"count":23,"filter":"raw"}],"_links":{"self":[{"href":"https:\/\/recyclingmachinery.org\/de\/wp-json\/wp\/v2\/posts\/5828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recyclingmachinery.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/recyclingmachinery.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/recyclingmachinery.org\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/recyclingmachinery.org\/de\/wp-json\/wp\/v2\/comments?post=5828"}],"version-history":[{"count":6,"href":"https:\/\/recyclingmachinery.org\/de\/wp-json\/wp\/v2\/posts\/5828\/revisions"}],"predecessor-version":[{"id":5839,"href":"https:\/\/recyclingmachinery.org\/de\/wp-json\/wp\/v2\/posts\/5828\/revisions\/5839"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/recyclingmachinery.org\/de\/wp-json\/wp\/v2\/media\/5837"}],"wp:attachment":[{"href":"https:\/\/recyclingmachinery.org\/de\/wp-json\/wp\/v2\/media?parent=5828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/recyclingmachinery.org\/de\/wp-json\/wp\/v2\/categories?post=5828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/recyclingmachinery.org\/de\/wp-json\/wp\/v2\/tags?post=5828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}